{"id":17478,"date":"2025-05-08T15:50:41","date_gmt":"2025-05-08T19:50:41","guid":{"rendered":"https:\/\/www.lediamant.ca\/?p=17478"},"modified":"2026-04-30T15:33:27","modified_gmt":"2026-04-30T19:33:27","slug":"montant-exceptionnel-evenement-benefice-2025","status":"publish","type":"post","link":"https:\/\/www.lediamant.ca\/fr\/montant-exceptionnel-evenement-benefice-2025","title":{"rendered":"Montant exceptionnel pour la campagne annuelle de financement"},"content":{"rendered":"<div class=\"item wysiwyg component-heading\" >\n<h2 class=\"wp-block-heading\">695 310 $ amass\u00e9s pour soutenir la mission du Diamant<\/h2>\n<\/div>\n\n<div class=\"item wysiwyg component-paragraph\" >\n<p><\/p>\n<\/div>\n\n<div class=\"item wysiwyg component-paragraph\" >\n<p>Le 7 mai, des centaines de donateurs et de donatrices qui ont \u00e0 c\u0153ur la mission du Diamant se sont r\u00e9uni-e-s pour l\u2019\u00c9v\u00e9nement-b\u00e9n\u00e9fice, une pr\u00e9sentation de la <strong>Caisse d\u2019\u00e9conomie solidaire Desjardins<\/strong> en collaboration avec l\u2019<strong>A\u00e9roport international Jean-Lesage de Qu\u00e9bec<\/strong> et <strong>Air Canada<\/strong>. Ensemble, ils ont d\u00e9couvert en avant-premi\u00e8re <em><a href=\"https:\/\/www.lediamant.ca\/fr\/programmation\/evenement-benefice-2025\">Hamlet, Prince du Danemark<\/a><\/em>, une cocr\u00e9ation de Robert Lepage et de Guillaume C\u00f4t\u00e9. En cl\u00f4ture de la soir\u00e9e, le montant recueilli dans le cadre de la campagne annuelle de financement, incluant notamment l\u2019\u00c9v\u00e9nement-b\u00e9n\u00e9fice et l\u2019encan virtuel, a \u00e9t\u00e9 d\u00e9voil\u00e9 : <strong>695 310 $<\/strong>.<\/p>\n<\/div>\n\n<div class=\"item wysiwyg component-heading\" >\n<h3 class=\"wp-block-heading\">Mot de Lynda, Robert et Steve<\/h3>\n<\/div>\n\n<div class=\"item wysiwyg component-image\" >\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"702\" src=\"https:\/\/www.lediamant.ca\/wp-content\/uploads\/2025\/05\/evenement-benefice-2025-robert-lynda-steve-1024x702.jpg\" alt=\"\" class=\"wp-image-17604\"\/ loading=\"lazy\" srcset=\"https:\/\/www.lediamant.ca\/wp-content\/uploads\/2025\/05\/evenement-benefice-2025-robert-lynda-steve-1024x702.jpg 1024w, https:\/\/www.lediamant.ca\/wp-content\/uploads\/2025\/05\/evenement-benefice-2025-robert-lynda-steve-700x480.jpg 700w, https:\/\/www.lediamant.ca\/wp-content\/uploads\/2025\/05\/evenement-benefice-2025-robert-lynda-steve-768x526.jpg 768w, https:\/\/www.lediamant.ca\/wp-content\/uploads\/2025\/05\/evenement-benefice-2025-robert-lynda-steve-400x274.jpg 400w, https:\/\/www.lediamant.ca\/wp-content\/uploads\/2025\/05\/evenement-benefice-2025-robert-lynda-steve.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Photo \u2014 H\u00e9l\u00e8ne Bouffard<\/figcaption><\/figure>\n<\/div>\n\n<div class=\"item component-spacer\" ><div class=\"container\">\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div>\n\n<div class=\"item wysiwyg component-paragraph\" >\n<p>\u00ab L&rsquo;attachement des publics et de la communaut\u00e9 d&rsquo;affaires envers Le Diamant est pr\u00e9cieux et se manifeste de plusieurs fa\u00e7ons. Nous sommes privil\u00e9gi\u00e9s de recevoir autant de reconnaissance de la part d&rsquo;amants, de m\u00e9c\u00e8nes et d&rsquo;entreprises qui croient en l&rsquo;importance des arts vivants. Leur appui est essentiel dans la poursuite de notre mission. Notre \u00e9v\u00e9nement-b\u00e9n\u00e9fice ainsi que le lancement du programme des Pierres pr\u00e9cieuses du Diamant ont grandement contribu\u00e9 aux succ\u00e8s de notre campagne annuelle de financement 2024-2025. Nous tenons \u00e0 remercier chaleureusement M<sup>me<\/sup> Olga Farman et M. Jean St-Gelais de leur implication ainsi que chaque donateur et donatrice qui ont pos\u00e9 un geste concret pour faire rayonner le lieu ici et \u00e0 l&rsquo;international. \u00bb<\/p>\n<\/div>\n\n<div class=\"item wysiwyg component-heading\" >\n<h3 class=\"wp-block-heading\">Mot de m<sup>me<\/sup> Farman et M. St-Gelais<\/h3>\n<\/div>\n\n<div class=\"item wysiwyg component-image\" >\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.lediamant.ca\/wp-content\/uploads\/2025\/05\/evenement-benefice-2025-mme-farman-m-st-gelais-1024x683.jpg\" alt=\"\" class=\"wp-image-17597\"\/ loading=\"lazy\" srcset=\"https:\/\/www.lediamant.ca\/wp-content\/uploads\/2025\/05\/evenement-benefice-2025-mme-farman-m-st-gelais-1024x683.jpg 1024w, https:\/\/www.lediamant.ca\/wp-content\/uploads\/2025\/05\/evenement-benefice-2025-mme-farman-m-st-gelais-700x467.jpg 700w, https:\/\/www.lediamant.ca\/wp-content\/uploads\/2025\/05\/evenement-benefice-2025-mme-farman-m-st-gelais-768x512.jpg 768w, https:\/\/www.lediamant.ca\/wp-content\/uploads\/2025\/05\/evenement-benefice-2025-mme-farman-m-st-gelais-400x267.jpg 400w, https:\/\/www.lediamant.ca\/wp-content\/uploads\/2025\/05\/evenement-benefice-2025-mme-farman-m-st-gelais.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\">Photo \u2014 Catherine T\u00e9treault<\/figcaption><\/figure>\n<\/div>\n\n<div class=\"item component-spacer\" ><div class=\"container\">\n<div style=\"height:25px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div>\n\n<div class=\"item wysiwyg component-paragraph\" >\n<p>\u00ab Le 7 mai, nous avons eu le grand privil\u00e8ge d\u2019assumer la copr\u00e9sidence d\u2019honneur de l\u2019\u00c9v\u00e9nement-b\u00e9n\u00e9fice du Diamant, en compagnie de donateur-trice-s et de partenaires profond\u00e9ment investi-e-s dans la vitalit\u00e9 des arts vivants.<\/p>\n<\/div>\n\n<div class=\"item wysiwyg component-paragraph\" >\n<p>Nous croyons fermement que la culture transforme les soci\u00e9t\u00e9s, et Le Diamant incarne pleinement cette conviction. \u00c0 la fois lieu de diffusion unique, p\u00f4le d\u2019attraction international et moteur d\u2019innovation artistique et citoyenne, il porte une vision ambitieuse que nous avons \u00e9t\u00e9 fiers de soutenir. Votre pr\u00e9sence, votre g\u00e9n\u00e9rosit\u00e9 et votre engagement lors de cette soir\u00e9e t\u00e9moignent d\u2019un attachement pr\u00e9cieux envers ce projet audacieux, qui contribue \u00e0 enrichir la production culturelle qu\u00e9b\u00e9coise et \u00e0 faire rayonner le Qu\u00e9bec \u00e0 partir de sa Capitale nationale.<\/p>\n<\/div>\n\n<div class=\"item wysiwyg component-paragraph\" >\n<p>Nous tenons \u00e0 vous remercier sinc\u00e8rement d\u2019avoir pos\u00e9 un geste concret pour appuyer cette mission. Gr\u00e2ce \u00e0 vous, Le Diamant peut continuer de rassembler les publics, d\u2019accueillir des \u0153uvres marquantes et de faire briller les arts vivants d\u2019ici et de l\u2019international. \u00bb<\/p>\n<\/div>\n\n<div class=\"item wysiwyg component-heading\" >\n<h3 class=\"wp-block-heading\" id=\"retour\">Retour sur l&rsquo;\u00e9v\u00e9nement<\/h3>\n<\/div>\n\n<div class=\"item wysiwyg component-paragraph\" >\n<p>La soir\u00e9e a d\u00e9but\u00e9 au 2<sup>e <\/sup>\u00e9tage dans le Foyer BMO o\u00f9 un cocktail d\u00eenatoire concoct\u00e9 par le <strong>Bistro<\/strong> <strong>La Cohue<\/strong> attendait les donateurs et les donatrices. Ces derniers ont pu donner un dernier coup d&rsquo;\u0153il aux lots de l\u2019encan virtuel et prendre quelques clich\u00e9s gr\u00e2ce \u00e0 Photobox Studio.<\/p>\n<\/div>\n\n<div class=\"item wysiwyg component-paragraph\" >\n<p>Consultez la galerie compl\u00e8te <a href=\"https:\/\/www.photoboxstudio.ca\/diamant7mai\" target=\"_blank\" rel=\"noreferrer noopener\">ici<\/a>.<\/p>\n<\/div>\n\n<div class=\"item wysiwyg component-images-slider\" >    <div class=\"js-images-slider images-slider images-slider--square\">\n\n        <nav data-slider-nav class=\"images-slider__navigation\" data-aria-label=\"Navigation du carrousel\">\n                            <button type=\"button\" aria-label=\"Pr\u00e9c\u00e9dent\" class=\"images-slider__button images-slider__button--prev\">\n                    <svg aria-hidden=\"true\" focusable=\"false\" width=\"20px\" height=\"19px\">\n                        <use xlink:href=\"#ico-arrow-right\"><\/use>\n                    <\/svg>\n                <\/button>\n                <button type=\"button\" aria-label=\"Suivant\" class=\"images-slider__button images-slider__button--next\">\n                    <svg aria-hidden=\"true\" focusable=\"false\" width=\"20px\" height=\"19px\">\n                        <use xlink:href=\"#ico-arrow-right\"><\/use>\n                    <\/svg>\n                <\/button>\n                    <\/nav>\n        <div class=\"images-slider__wrapper\" data-slider-items role=\"list\">\n                                            <div class=\"images-slider__item\">\n                    <img decoding=\"async\" src=\"https:\/\/www.lediamant.ca\/wp-content\/uploads\/2025\/05\/evenement-benefice-2025-photobox-01.jpg\" data-src=\"https:\/\/www.lediamant.ca\/wp-content\/uploads\/2025\/05\/evenement-benefice-2025-photobox-01.jpg\" alt=\"Photo de deux invit\u00e9s \u00e0 l\u2019\u00e9v\u00e9nement-b\u00e9n\u00e9fice 2025 du Th\u00e9\u00e2tre Le Diamant \u00e0 Qu\u00e9bec, dont Yvon Charest, souriants.\" class=\"images-slider__img tns-lazy-img\" loading=\"lazy\">\n                                            <span class=\"images-slider__copyright\">Photo \u2014 Photobox Studio<\/span>\n                                    <\/div>\n                                            <div class=\"images-slider__item\">\n                    <img decoding=\"async\" src=\"\" data-src=\"https:\/\/www.lediamant.ca\/wp-content\/uploads\/2025\/05\/evenement-benefice-2025-photobox-02.jpg\" alt=\"Photo de deux femmes \u00e0 l\u2019\u00e9v\u00e9nement-b\u00e9n\u00e9fice 2025 du Th\u00e9\u00e2tre Le Diamant \u00e0 Qu\u00e9bec, souriantes devant un mur de logos.\" class=\"images-slider__img tns-lazy-img\" loading=\"lazy\">\n                                            <span class=\"images-slider__copyright\">Photo \u2014 Photobox Studio<\/span>\n                                    <\/div>\n                                            <div class=\"images-slider__item\">\n                    <img decoding=\"async\" src=\"\" data-src=\"https:\/\/www.lediamant.ca\/wp-content\/uploads\/2025\/05\/evenement-benefice-2025-photobox-03.jpg\" alt=\"Photo de deux invit\u00e9s \u00e0 l\u2019\u00e9v\u00e9nement-b\u00e9n\u00e9fice 2025 du Th\u00e9\u00e2tre Le Diamant \u00e0 Qu\u00e9bec.\" class=\"images-slider__img tns-lazy-img\" loading=\"lazy\">\n                                            <span class=\"images-slider__copyright\">Photo \u2014 Photobox Studio<\/span>\n                                    <\/div>\n                                            <div class=\"images-slider__item\">\n                    <img decoding=\"async\" src=\"\" data-src=\"https:\/\/www.lediamant.ca\/wp-content\/uploads\/2025\/05\/evenement-benefice-2025-photobox-04.jpg\" alt=\"Photo d\u2019invit\u00e9s \u00e0 l\u2019\u00e9v\u00e9nement-b\u00e9n\u00e9fice 2025 du Th\u00e9\u00e2tre Le Diamant.\" class=\"images-slider__img tns-lazy-img\" loading=\"lazy\">\n                                            <span class=\"images-slider__copyright\">Photo \u2014 Photobox Studio<\/span>\n                                    <\/div>\n                                            <div class=\"images-slider__item\">\n                    <img decoding=\"async\" src=\"\" data-src=\"https:\/\/www.lediamant.ca\/wp-content\/uploads\/2025\/05\/evenement-benefice-2025-photobox-05.jpg\" alt=\"Photo d\u2019invit\u00e9s \u00e0 l\u2019\u00e9v\u00e9nement-b\u00e9n\u00e9fice 2025 du Th\u00e9\u00e2tre Le Diamant, dont Lynda Beaulieu, cofondatrice et pr\u00e9sidente.\" class=\"images-slider__img tns-lazy-img\" loading=\"lazy\">\n                                            <span class=\"images-slider__copyright\">Photo \u2014 Photobox Studio<\/span>\n                                    <\/div>\n                                            <div class=\"images-slider__item\">\n                    <img decoding=\"async\" src=\"\" data-src=\"https:\/\/www.lediamant.ca\/wp-content\/uploads\/2025\/05\/evenement-benefice-2025-photobox-06.jpg\" alt=\"Photo d'invit\u00e9s \u00e0 l'\u00e9v\u00e9nement-b\u00e9n\u00e9fice 2025 du th\u00e9\u00e2tre Le Diamant.\" class=\"images-slider__img tns-lazy-img\" loading=\"lazy\">\n                                            <span class=\"images-slider__copyright\">Photo \u2014 Photobox Studio<\/span>\n                                    <\/div>\n                                            <div class=\"images-slider__item\">\n                    <img decoding=\"async\" src=\"\" data-src=\"https:\/\/www.lediamant.ca\/wp-content\/uploads\/2025\/05\/evenement-benefice-2025-photobox-07.jpg\" alt=\"Photo d\u2019invit\u00e9s \u00e0 l\u2019\u00e9v\u00e9nement-b\u00e9n\u00e9fice 2025 du Th\u00e9\u00e2tre Le Diamant, dont Olga Farman, copr\u00e9sidente d\u2019honneur.\" class=\"images-slider__img tns-lazy-img\" loading=\"lazy\">\n                                            <span class=\"images-slider__copyright\">Photo \u2014 Photobox Studio<\/span>\n                                    <\/div>\n                                            <div class=\"images-slider__item\">\n                    <img decoding=\"async\" src=\"\" data-src=\"https:\/\/www.lediamant.ca\/wp-content\/uploads\/2025\/05\/evenement-benefice-2025-photobox-08.jpg\" alt=\"Photo d\u2019invit\u00e9s \u00e0 l\u2019\u00e9v\u00e9nement-b\u00e9n\u00e9fice du Th\u00e9\u00e2tre Le Diamant, dont \u00c9tienne Cummings de l\u2019A\u00e9roport international Jean-Lesage.\" class=\"images-slider__img tns-lazy-img\" loading=\"lazy\">\n                                            <span class=\"images-slider__copyright\">Photo \u2014 Photobox Studio<\/span>\n                                    <\/div>\n                                            <div class=\"images-slider__item\">\n                    <img decoding=\"async\" src=\"\" data-src=\"https:\/\/www.lediamant.ca\/wp-content\/uploads\/2025\/05\/evenement-benefice-2025-photobox-09.jpg\" alt=\"Photo d\u2019Alain Fortier, membre du conseil d\u2019administration du Th\u00e9\u00e2tre Le Diamant, avec sa conjointe \u00e0 l\u2019\u00e9v\u00e9nement-b\u00e9n\u00e9fice 2025.\" class=\"images-slider__img tns-lazy-img\" loading=\"lazy\">\n                                            <span class=\"images-slider__copyright\">Photo \u2014 Photobox Studio<\/span>\n                                    <\/div>\n                                            <div class=\"images-slider__item\">\n                    <img decoding=\"async\" src=\"\" data-src=\"https:\/\/www.lediamant.ca\/wp-content\/uploads\/2025\/05\/evenement-benefice-2025-photobox-11.jpg\" alt=\"Photo de l\u2019\u00e9quipe d\u2019accueil du Th\u00e9\u00e2tre Le Diamant lors de l\u2019\u00e9v\u00e9nement-b\u00e9n\u00e9fice 2025 \u00e0 Qu\u00e9bec.\" class=\"images-slider__img tns-lazy-img\" loading=\"lazy\">\n                                            <span class=\"images-slider__copyright\">Photo \u2014 Photobox Studio<\/span>\n                                    <\/div>\n                                            <div class=\"images-slider__item\">\n                    <img decoding=\"async\" src=\"\" data-src=\"https:\/\/www.lediamant.ca\/wp-content\/uploads\/2025\/05\/evenement-benefice-2025-photobox-12-1.jpg\" alt=\"Photo de l\u2019\u00e9quipe Ex Machina, incluant Robert Lepage, avec l\u2019\u00e9quipe de production du Th\u00e9\u00e2tre Le Diamant lors de l\u2019\u00e9v\u00e9nement-b\u00e9n\u00e9fice 2025 \u00e0 Qu\u00e9bec.\" class=\"images-slider__img tns-lazy-img\" loading=\"lazy\">\n                                            <span class=\"images-slider__copyright\">Photo \u2014 Photobox Studio<\/span>\n                                    <\/div>\n                    <\/div>\n    <\/div>\n<\/div>\n\n<div class=\"item wysiwyg component-heading\" >\n<h3 class=\"wp-block-heading\">Formule VIP<\/h3>\n<\/div>\n\n<div class=\"item wysiwyg component-paragraph\" >\n<p>Pendant ce temps se d\u00e9roulait au Studio Lepage Beaulieu une activit\u00e9 unique. Cette ann\u00e9e, une formule <em>VIP<\/em> a permis \u00e0 130 donateurs et donatrices de bonifier leur exp\u00e9rience et d\u2019assister \u00e0 un \u00e9change exclusif anim\u00e9 par Guy Jodoin entre les cofondateurs du Diamant, Lynda Beaulieu et Robert Lepage. D\u2019une dur\u00e9e de 60 minutes, le duo a r\u00e9pondu aux questions de l&rsquo;animateur en plus de d\u00e9voiler des anecdotes in\u00e9dites. <strong>Lora Films<\/strong> a r\u00e9alis\u00e9 la captation vid\u00e9o de l&rsquo;\u00e9v\u00e9nement, qui sera disponible tr\u00e8s bient\u00f4t.<\/p>\n<\/div>\n\n<div class=\"item wysiwyg component-images-slider\" >    <div class=\"js-images-slider images-slider images-slider--landscape\">\n\n        <nav data-slider-nav class=\"images-slider__navigation\" data-aria-label=\"Navigation du carrousel\">\n                            <button type=\"button\" aria-label=\"Pr\u00e9c\u00e9dent\" class=\"images-slider__button images-slider__button--prev\">\n                    <svg aria-hidden=\"true\" focusable=\"false\" width=\"20px\" height=\"19px\">\n                        <use xlink:href=\"#ico-arrow-right\"><\/use>\n                    <\/svg>\n                <\/button>\n                <button type=\"button\" aria-label=\"Suivant\" class=\"images-slider__button images-slider__button--next\">\n                    <svg aria-hidden=\"true\" focusable=\"false\" width=\"20px\" height=\"19px\">\n                        <use xlink:href=\"#ico-arrow-right\"><\/use>\n                    <\/svg>\n                <\/button>\n                    <\/nav>\n        <div class=\"images-slider__wrapper\" data-slider-items role=\"list\">\n                                            <div class=\"images-slider__item\">\n                    <img decoding=\"async\" src=\"https:\/\/www.lediamant.ca\/wp-content\/uploads\/2025\/05\/evenement-benefice-2025-mme-vip-01-e1746719078308.jpg\" data-src=\"https:\/\/www.lediamant.ca\/wp-content\/uploads\/2025\/05\/evenement-benefice-2025-mme-vip-01-e1746719078308.jpg\" alt=\"Photo en plong\u00e9e de l\u2019\u00e9v\u00e9nement-b\u00e9n\u00e9fice 2025 du Diamant \u00e0 Qu\u00e9bec, avec les invit\u00e9s en salle et Robert Lepage, Lynda Beaulieu et Guy Jodoin sur sc\u00e8ne.\" class=\"images-slider__img tns-lazy-img\" loading=\"lazy\">\n                                            <span class=\"images-slider__copyright\">Photo \u2014 Catherine T\u00e9treault<\/span>\n                                    <\/div>\n                                            <div class=\"images-slider__item\">\n                    <img decoding=\"async\" src=\"\" data-src=\"https:\/\/www.lediamant.ca\/wp-content\/uploads\/2025\/05\/evenement-benefice-2025-mme-vip-02.jpg\" alt=\"Photo de l\u2019\u00e9v\u00e9nement-b\u00e9n\u00e9fice 2025 du Diamant \u00e0 Qu\u00e9bec, avec Robert Lepage, Lynda Beaulieu et Guy Jodoin sur sc\u00e8ne.\" class=\"images-slider__img tns-lazy-img\" loading=\"lazy\">\n                                            <span class=\"images-slider__copyright\">Photo \u2014 Catherine T\u00e9treault<\/span>\n                                    <\/div>\n                                            <div class=\"images-slider__item\">\n                    <img decoding=\"async\" src=\"\" data-src=\"https:\/\/www.lediamant.ca\/wp-content\/uploads\/2025\/05\/evenement-benefice-2025-mme-vip-03.jpg\" alt=\"Photo de l\u2019\u00e9v\u00e9nement-b\u00e9n\u00e9fice 2025 du Diamant \u00e0 Qu\u00e9bec, avec Robert Lepage, cofondateur, sur sc\u00e8ne devant les spectateurs.\" class=\"images-slider__img tns-lazy-img\" loading=\"lazy\">\n                                            <span class=\"images-slider__copyright\">Photo \u2014 Catherine T\u00e9treault<\/span>\n                                    <\/div>\n                                            <div class=\"images-slider__item\">\n                    <img decoding=\"async\" src=\"\" data-src=\"https:\/\/www.lediamant.ca\/wp-content\/uploads\/2025\/05\/evenement-benefice-2025-mme-vip-04.jpg\" alt=\"Photo de l\u2019\u00e9v\u00e9nement-b\u00e9n\u00e9fice 2025 du Diamant \u00e0 Qu\u00e9bec, avec Robert Lepage, Lynda Beaulieu et Guy Jodoin sur sc\u00e8ne devant les spectateurs.\" class=\"images-slider__img tns-lazy-img\" loading=\"lazy\">\n                                            <span class=\"images-slider__copyright\">Photo \u2014 Catherine T\u00e9treault<\/span>\n                                    <\/div>\n                    <\/div>\n    <\/div>\n<\/div>\n\n<div class=\"item component-spacer\" ><div class=\"container\">\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div>\n\n<div class=\"item wysiwyg component-paragraph\" >\n<p>Alors que les donateurs et donatrices se retrouvaient au Foyer, un coup de gong a marqu\u00e9 l\u2019entr\u00e9e en salle pour l\u2019avant-premi\u00e8re de <em>Hamlet, Prince du Danemark<\/em>, pr\u00e9sent\u00e9e dans le cadre de l\u2019\u00c9v\u00e9nement-b\u00e9n\u00e9fice. Une fois les invit\u00e9s install\u00e9s dans la Salle Hydro-Qu\u00e9bec, Lynda Beaulieu et Steve Labrie ont adress\u00e9 un mot de bienvenue, avant de c\u00e9der la parole aux pr\u00e9sidents d\u2019honneur ainsi qu\u2019\u00e0 M. Marc Picard, directeur g\u00e9n\u00e9ral de la <strong>Caisse d\u2019\u00e9conomie solidaire Desjardins<\/strong>, pr\u00e9sentateur de la soir\u00e9e.<\/p>\n<\/div>\n\n<div class=\"item wysiwyg component-paragraph\" >\n<p><em>Hamlet, Prince du Danemark<\/em> a plong\u00e9 les spectateurs dans un monde aux apparences trompeuses, o\u00f9 spectres et humains se c\u00f4toient dans une sc\u00e9nographie minimaliste. Cette relecture m\u00e9taphorique du r\u00e9cit shakespearien a charm\u00e9 l\u2019ensemble des invit\u00e9s.  \u00c0 l\u2019issue du spectacle, les pr\u00e9sidents d\u2019honneur, M<sup>me<\/sup> Olga Farman et M. Jean St-Gelais, les cofondateurs du Diamant, Lynda Beaulieu et Robert Lepage, le directeur g\u00e9n\u00e9ral Steve Labrie, le chor\u00e9graphe et danseur Guillaume C\u00f4t\u00e9 ainsi que M. Marc Picard sont mont\u00e9s sur sc\u00e8ne pour d\u00e9voiler avec fiert\u00e9 le montant recueilli dans le cadre de la campagne annuelle de financement priv\u00e9 : <strong>695 310 $<\/strong>.<\/p>\n<\/div>\n\n<div class=\"item wysiwyg component-paragraph\" >\n<p>Ce montant total inclut tous les dons des programmes suivants :<\/p>\n<\/div>\n\n<div class=\"item wysiwyg component-list\" >\n<ul class=\"wp-block-list\">\n<li>Soyons solidaires \/ Appuyez la mission ;<\/li>\n\n\n\n<li>Donnez au suivant (Billets du c\u0153ur Desjardins) ;<\/li>\n\n\n\n<li>Un Fauteuil \u00e0 votre nom ;<\/li>\n\n\n\n<li>Les Pierres pr\u00e9cieuses du Diamant ;<\/li>\n\n\n\n<li>Les Amants du Diamant ;<\/li>\n\n\n\n<li>L\u2019encan virtuel ;<\/li>\n\n\n\n<li>L\u2019\u00e9v\u00e9nement-b\u00e9n\u00e9fice.<\/li>\n<\/ul>\n<\/div>\n\n<div class=\"item wysiwyg component-images-slider\" >    <div class=\"js-images-slider images-slider images-slider--landscape\">\n\n        <nav data-slider-nav class=\"images-slider__navigation\" data-aria-label=\"Navigation du carrousel\">\n                            <button type=\"button\" aria-label=\"Pr\u00e9c\u00e9dent\" class=\"images-slider__button images-slider__button--prev\">\n                    <svg aria-hidden=\"true\" focusable=\"false\" width=\"20px\" height=\"19px\">\n                        <use xlink:href=\"#ico-arrow-right\"><\/use>\n                    <\/svg>\n                <\/button>\n                <button type=\"button\" aria-label=\"Suivant\" class=\"images-slider__button images-slider__button--next\">\n                    <svg aria-hidden=\"true\" focusable=\"false\" width=\"20px\" height=\"19px\">\n                        <use xlink:href=\"#ico-arrow-right\"><\/use>\n                    <\/svg>\n                <\/button>\n                    <\/nav>\n        <div class=\"images-slider__wrapper\" data-slider-items role=\"list\">\n                                            <div class=\"images-slider__item\">\n                    <img decoding=\"async\" src=\"https:\/\/www.lediamant.ca\/wp-content\/uploads\/2025\/05\/evenement-benefice-2025-montant-carrousel.jpg\" data-src=\"https:\/\/www.lediamant.ca\/wp-content\/uploads\/2025\/05\/evenement-benefice-2025-montant-carrousel.jpg\" alt=\"Photo du d\u00e9voilement du montant amass\u00e9 \u00e0 l\u2019\u00e9v\u00e9nement-b\u00e9n\u00e9fice 2025 du Th\u00e9\u00e2tre Le Diamant, dans la salle devant les spectateurs \u00e0 Qu\u00e9bec.\" class=\"images-slider__img tns-lazy-img\" loading=\"lazy\">\n                                            <span class=\"images-slider__copyright\">Photo \u2014 Catherine T\u00e9treault<\/span>\n                                    <\/div>\n                                            <div class=\"images-slider__item\">\n                    <img decoding=\"async\" src=\"\" data-src=\"https:\/\/www.lediamant.ca\/wp-content\/uploads\/2025\/05\/evenement-benefice-2025-artistes-carrousel.jpg\" alt=\"Photo du salut final du spectacle Hamlet, Prince du Danemark lors de l\u2019\u00e9v\u00e9nement-b\u00e9n\u00e9fice 2025 du Diamant, avec Guillaume C\u00f4t\u00e9.\" class=\"images-slider__img tns-lazy-img\" loading=\"lazy\">\n                                            <span class=\"images-slider__copyright\">Photo \u2014 Catherine T\u00e9treault<\/span>\n                                    <\/div>\n                    <\/div>\n    <\/div>\n<\/div>\n\n<div class=\"item component-spacer\" ><div class=\"container\">\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div>\n\n<div class=\"item wysiwyg component-paragraph\" >\n<p>Le Diamant souhaite remercier chaleureusement ses <a href=\"https:\/\/www.lediamant.ca\/fr\/partenaires\">pr\u00e9cieux partenaires<\/a>. Leur apport essentiel, combin\u00e9 \u00e0 l\u2019engagement de plusieurs autres entreprises, a rendu possible la pr\u00e9sentation de cet \u00e9v\u00e9nement et a grandement contribu\u00e9 aux succ\u00e8s de la campagne annuelle de financement priv\u00e9.<\/p>\n<\/div>\n\n<div class=\"item component-columns\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"item wysiwyg component-html\" >\n<h5 style=\"margin-bottom: 6rem\" class=\"push-b-xs-65\">Une pr\u00e9sentation de<\/h5>\n<div style=\"list-style: none; display: flex; align-items: center; flex-wrap: wrap;\">\n    <img src=\"https:\/\/www.lediamant.ca\/wp-content\/uploads\/2023\/12\/Caisse-deconomie-solidaire.svg\" class=\"\" alt=\"Caisse d'\u00e9conomie solidaire\" decoding=\"async\" loading=\"lazy\" style=\"height:60px;margin-right: 6rem; margin-bottom: 6rem;\">\n<\/div>\n<\/div>\n\n<div class=\"item wysiwyg component-html\" >\n<h5 style=\"margin-bottom: 6rem\" class=\"push-b-xs-65\">Partenaires de services<\/h5>\n<div style=\"list-style: none; display: flex; align-items: center; flex-wrap: wrap;\">\n    <img src=\"https:\/\/www.lediamant.ca\/wp-content\/uploads\/2024\/10\/Lora-Createur-video.svg\" class=\"\" alt=\"Lora Cr\u00e9ateur vid\u00e9o\" decoding=\"async\" loading=\"lazy\" style=\"margin-right: 6rem; margin-bottom: 6rem; height: 35px\">\n    <img src=\"https:\/\/www.lediamant.ca\/wp-content\/uploads\/2024\/04\/Bistro-La-Cohue.svg\" class=\"\" alt=\"Bistro La Cohue\" decoding=\"async\" loading=\"lazy\" style=\"margin-right: 6rem; margin-bottom: 6rem; margin-bottom: 6rem; margin-bottom: 6rem; height: 65px\">\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"item wysiwyg component-html\" >\n<h5 style=\"margin-bottom: 6rem\" class=\"push-b-xs-65\">En collaboration avec<\/h5>\n<div style=\"list-style: none; display: flex; align-items: center; flex-wrap: wrap;\">\n    <img src=\"https:\/\/www.lediamant.ca\/wp-content\/uploads\/2025\/01\/Aeroport-international-Jean-Lesage-de-Quebec.svg\" class=\"\" alt=\"A\u00e9roport international Jean-Lesage de Qu\u00e9bec (YQB)\" decoding=\"async\" loading=\"lazy\" style=\"margin-right: 6rem; margin-bottom: 6rem; margin-bottom: 6rem; margin-bottom: 6rem; height: 45px\">\n    <img src=\"https:\/\/www.lediamant.ca\/wp-content\/uploads\/2024\/04\/Air-Canada.svg\" class=\"\" alt=\"Air Canada\" decoding=\"async\" loading=\"lazy\" style=\"margin-right: 6rem; margin-bottom: 6rem; height: 25px\">\n<\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n\n<div class=\"item wysiwyg component-paragraph\" >\n<p>Gr\u00e2ce \u00e0 tous ces engagements et les dons g\u00e9n\u00e9reux, Le Diamant rayonne et continue de remplir ses promesses :<\/p>\n<\/div>\n\n<div class=\"item wysiwyg component-list\" >\n<ul class=\"wp-block-list\">\n<li>\u00catre un point de convergence et d\u2019innovation pour les artistes, les cr\u00e9ateurs et les publics ;<\/li>\n\n\n\n<li>Offrir des productions audacieuses d\u2019ici et d\u2019ailleurs \u00e0 la population de Qu\u00e9bec ainsi qu\u2019\u00e0 la client\u00e8le touristique ;<\/li>\n\n\n\n<li>Participer activement \u00e0 l\u2019inclusion, au d\u00e9veloppement de la communaut\u00e9 et \u00e0 l\u2019effervescence \u00e9conomique de la r\u00e9gion ;<\/li>\n\n\n\n<li>Devenir un levier de revitalisation pour la place D\u2019Youville.<\/li>\n<\/ul>\n<\/div>\n\n<div class=\"item component-spacer\" ><div class=\"container\">\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div>\n\n<div class=\"item wysiwyg component-heading\" >\n<h2 class=\"wp-block-heading\">Mission<\/h2>\n<\/div>\n\n<div class=\"item wysiwyg component-paragraph\" >\n<p>Inspir\u00e9 par l\u2019artiste de renomm\u00e9e internationale Robert Lepage, Le Diamant est un diffuseur et le lieu de cr\u00e9ation de la compagnie Ex Machina. Situ\u00e9 au c\u0153ur de la ville de Qu\u00e9bec, cet espace au concept architectural unique invite les publics \u00e0 d\u00e9couvrir la th\u00e9\u00e2tralit\u00e9 sous toutes ses formes dans un environnement accessible et accueillant<\/p>\n<\/div>\n\n<div class=\"item wysiwyg component-paragraph\" >\n<p><\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"Le 7 mai, des centaines de donateurs et de donatrices qui ont \u00e0 c\u0153ur la mission du Diamant se sont r\u00e9uni-e-s pour l\u2019\u00c9v\u00e9nement-b\u00e9n\u00e9fice, une pr\u00e9sentation de la Caisse d\u2019\u00e9conomie solidaire Desjardins en collaboration avec l\u2019A\u00e9roport international Jean-Lesage de Qu\u00e9bec et Air Canada.","protected":false},"author":2,"featured_media":17658,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[43],"tags":[],"class_list":["post-17478","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-communique"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Montant exceptionnel pour la campagne annuelle de financement - Le Diamant<\/title>\n<meta name=\"description\" content=\"Le 7 mai, des centaines de donateurs et de donatrices qui ont \u00e0 c\u0153ur la mission du Diamant se sont r\u00e9uni-e-s pour l\u2019\u00c9v\u00e9nement-b\u00e9n\u00e9fice.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lediamant.ca\/fr\/montant-exceptionnel-evenement-benefice-2025\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Montant exceptionnel pour la campagne annuelle de financement| Le Diamant\" \/>\n<meta property=\"og:description\" content=\"695 310 $ amass\u00e9s pour soutenir la mission du Diamant\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lediamant.ca\/fr\/montant-exceptionnel-evenement-benefice-2025\" \/>\n<meta property=\"og:site_name\" content=\"Le Diamant\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/lediamantqc\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-08T19:50:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-30T19:33:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lediamant.ca\/wp-content\/uploads\/2025\/05\/evenement-benefice-2025-article-header.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1366\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Le Diamant\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@lediamant_qc\" \/>\n<meta name=\"twitter:site\" content=\"@lediamant_qc\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Le Diamant\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.lediamant.ca\/fr\/montant-exceptionnel-evenement-benefice-2025#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.lediamant.ca\/fr\/montant-exceptionnel-evenement-benefice-2025\"},\"author\":{\"name\":\"Le Diamant\",\"@id\":\"https:\/\/www.lediamant.ca\/fr\/#\/schema\/person\/1df7cc9f6c6e5901ce19062096c025af\"},\"headline\":\"Montant exceptionnel pour la campagne annuelle de financement\",\"datePublished\":\"2025-05-08T19:50:41+00:00\",\"dateModified\":\"2026-04-30T19:33:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.lediamant.ca\/fr\/montant-exceptionnel-evenement-benefice-2025\"},\"wordCount\":1067,\"publisher\":{\"@id\":\"https:\/\/www.lediamant.ca\/fr\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.lediamant.ca\/fr\/montant-exceptionnel-evenement-benefice-2025#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lediamant.ca\/wp-content\/uploads\/2025\/05\/evenement-benefice-2025-article-header.jpg\",\"articleSection\":[\"Communiqu\u00e9\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lediamant.ca\/fr\/montant-exceptionnel-evenement-benefice-2025\",\"url\":\"https:\/\/www.lediamant.ca\/fr\/montant-exceptionnel-evenement-benefice-2025\",\"name\":\"Montant exceptionnel pour la campagne annuelle de financement - Le Diamant\",\"isPartOf\":{\"@id\":\"https:\/\/www.lediamant.ca\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.lediamant.ca\/fr\/montant-exceptionnel-evenement-benefice-2025#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.lediamant.ca\/fr\/montant-exceptionnel-evenement-benefice-2025#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.lediamant.ca\/wp-content\/uploads\/2025\/05\/evenement-benefice-2025-article-header.jpg\",\"datePublished\":\"2025-05-08T19:50:41+00:00\",\"dateModified\":\"2026-04-30T19:33:27+00:00\",\"description\":\"Le 7 mai, des centaines de donateurs et de donatrices qui ont \u00e0 c\u0153ur la mission du Diamant se sont r\u00e9uni-e-s pour l\u2019\u00c9v\u00e9nement-b\u00e9n\u00e9fice.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lediamant.ca\/fr\/montant-exceptionnel-evenement-benefice-2025#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lediamant.ca\/fr\/montant-exceptionnel-evenement-benefice-2025\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lediamant.ca\/fr\/montant-exceptionnel-evenement-benefice-2025#primaryimage\",\"url\":\"https:\/\/www.lediamant.ca\/wp-content\/uploads\/2025\/05\/evenement-benefice-2025-article-header.jpg\",\"contentUrl\":\"https:\/\/www.lediamant.ca\/wp-content\/uploads\/2025\/05\/evenement-benefice-2025-article-header.jpg\",\"width\":2048,\"height\":1366,\"caption\":\"Photo du d\u00e9voilement du montant amass\u00e9 lors de l\u2019\u00e9v\u00e9nement-b\u00e9n\u00e9fice 2025 du Th\u00e9\u00e2tre Le Diamant, avec Lynda Beaulieu et Robert Lepage.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lediamant.ca\/fr\/montant-exceptionnel-evenement-benefice-2025#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.lediamant.ca\/fr\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Montant exceptionnel pour la campagne annuelle de financement\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lediamant.ca\/fr\/#website\",\"url\":\"https:\/\/www.lediamant.ca\/fr\/\",\"name\":\"Le Diamant\",\"description\":\"Salle de spectacle situ\u00e9e \u00e0 place D&#039;Youville, Qu\u00e9bec (Canada). D\u00e9couvrez notre programmation.\",\"publisher\":{\"@id\":\"https:\/\/www.lediamant.ca\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lediamant.ca\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.lediamant.ca\/fr\/#organization\",\"name\":\"Le Diamant\",\"url\":\"https:\/\/www.lediamant.ca\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lediamant.ca\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.lediamant.ca\/wp-content\/uploads\/2023\/05\/le-diamant-logo.png\",\"contentUrl\":\"https:\/\/www.lediamant.ca\/wp-content\/uploads\/2023\/05\/le-diamant-logo.png\",\"width\":1000,\"height\":750,\"caption\":\"Le Diamant\"},\"image\":{\"@id\":\"https:\/\/www.lediamant.ca\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/lediamantqc\/\",\"https:\/\/x.com\/lediamant_qc\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.lediamant.ca\/fr\/#\/schema\/person\/1df7cc9f6c6e5901ce19062096c025af\",\"name\":\"Le Diamant\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.lediamant.ca\/fr\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/987afa0f07c5e880e415fd6bbdc5cc7ccbd67354d810536804d8f515d64bd014?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/987afa0f07c5e880e415fd6bbdc5cc7ccbd67354d810536804d8f515d64bd014?s=96&d=mm&r=g\",\"caption\":\"Le Diamant\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Montant exceptionnel pour la campagne annuelle de financement - Le Diamant","description":"Le 7 mai, des centaines de donateurs et de donatrices qui ont \u00e0 c\u0153ur la mission du Diamant se sont r\u00e9uni-e-s pour l\u2019\u00c9v\u00e9nement-b\u00e9n\u00e9fice.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lediamant.ca\/fr\/montant-exceptionnel-evenement-benefice-2025","og_locale":"fr_FR","og_type":"article","og_title":"Montant exceptionnel pour la campagne annuelle de financement| Le Diamant","og_description":"695 310 $ amass\u00e9s pour soutenir la mission du Diamant","og_url":"https:\/\/www.lediamant.ca\/fr\/montant-exceptionnel-evenement-benefice-2025","og_site_name":"Le Diamant","article_publisher":"https:\/\/www.facebook.com\/lediamantqc\/","article_published_time":"2025-05-08T19:50:41+00:00","article_modified_time":"2026-04-30T19:33:27+00:00","og_image":[{"width":2048,"height":1366,"url":"https:\/\/www.lediamant.ca\/wp-content\/uploads\/2025\/05\/evenement-benefice-2025-article-header.jpg","type":"image\/jpeg"}],"author":"Le Diamant","twitter_card":"summary_large_image","twitter_creator":"@lediamant_qc","twitter_site":"@lediamant_qc","twitter_misc":{"\u00c9crit par":"Le Diamant","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lediamant.ca\/fr\/montant-exceptionnel-evenement-benefice-2025#article","isPartOf":{"@id":"https:\/\/www.lediamant.ca\/fr\/montant-exceptionnel-evenement-benefice-2025"},"author":{"name":"Le Diamant","@id":"https:\/\/www.lediamant.ca\/fr\/#\/schema\/person\/1df7cc9f6c6e5901ce19062096c025af"},"headline":"Montant exceptionnel pour la campagne annuelle de financement","datePublished":"2025-05-08T19:50:41+00:00","dateModified":"2026-04-30T19:33:27+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lediamant.ca\/fr\/montant-exceptionnel-evenement-benefice-2025"},"wordCount":1067,"publisher":{"@id":"https:\/\/www.lediamant.ca\/fr\/#organization"},"image":{"@id":"https:\/\/www.lediamant.ca\/fr\/montant-exceptionnel-evenement-benefice-2025#primaryimage"},"thumbnailUrl":"https:\/\/www.lediamant.ca\/wp-content\/uploads\/2025\/05\/evenement-benefice-2025-article-header.jpg","articleSection":["Communiqu\u00e9"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.lediamant.ca\/fr\/montant-exceptionnel-evenement-benefice-2025","url":"https:\/\/www.lediamant.ca\/fr\/montant-exceptionnel-evenement-benefice-2025","name":"Montant exceptionnel pour la campagne annuelle de financement - Le Diamant","isPartOf":{"@id":"https:\/\/www.lediamant.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lediamant.ca\/fr\/montant-exceptionnel-evenement-benefice-2025#primaryimage"},"image":{"@id":"https:\/\/www.lediamant.ca\/fr\/montant-exceptionnel-evenement-benefice-2025#primaryimage"},"thumbnailUrl":"https:\/\/www.lediamant.ca\/wp-content\/uploads\/2025\/05\/evenement-benefice-2025-article-header.jpg","datePublished":"2025-05-08T19:50:41+00:00","dateModified":"2026-04-30T19:33:27+00:00","description":"Le 7 mai, des centaines de donateurs et de donatrices qui ont \u00e0 c\u0153ur la mission du Diamant se sont r\u00e9uni-e-s pour l\u2019\u00c9v\u00e9nement-b\u00e9n\u00e9fice.","breadcrumb":{"@id":"https:\/\/www.lediamant.ca\/fr\/montant-exceptionnel-evenement-benefice-2025#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lediamant.ca\/fr\/montant-exceptionnel-evenement-benefice-2025"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lediamant.ca\/fr\/montant-exceptionnel-evenement-benefice-2025#primaryimage","url":"https:\/\/www.lediamant.ca\/wp-content\/uploads\/2025\/05\/evenement-benefice-2025-article-header.jpg","contentUrl":"https:\/\/www.lediamant.ca\/wp-content\/uploads\/2025\/05\/evenement-benefice-2025-article-header.jpg","width":2048,"height":1366,"caption":"Photo du d\u00e9voilement du montant amass\u00e9 lors de l\u2019\u00e9v\u00e9nement-b\u00e9n\u00e9fice 2025 du Th\u00e9\u00e2tre Le Diamant, avec Lynda Beaulieu et Robert Lepage."},{"@type":"BreadcrumbList","@id":"https:\/\/www.lediamant.ca\/fr\/montant-exceptionnel-evenement-benefice-2025#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.lediamant.ca\/fr"},{"@type":"ListItem","position":2,"name":"Montant exceptionnel pour la campagne annuelle de financement"}]},{"@type":"WebSite","@id":"https:\/\/www.lediamant.ca\/fr\/#website","url":"https:\/\/www.lediamant.ca\/fr\/","name":"Le Diamant","description":"Salle de spectacle situ\u00e9e \u00e0 place D&#039;Youville, Qu\u00e9bec (Canada). D\u00e9couvrez notre programmation.","publisher":{"@id":"https:\/\/www.lediamant.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lediamant.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.lediamant.ca\/fr\/#organization","name":"Le Diamant","url":"https:\/\/www.lediamant.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lediamant.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.lediamant.ca\/wp-content\/uploads\/2023\/05\/le-diamant-logo.png","contentUrl":"https:\/\/www.lediamant.ca\/wp-content\/uploads\/2023\/05\/le-diamant-logo.png","width":1000,"height":750,"caption":"Le Diamant"},"image":{"@id":"https:\/\/www.lediamant.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/lediamantqc\/","https:\/\/x.com\/lediamant_qc"]},{"@type":"Person","@id":"https:\/\/www.lediamant.ca\/fr\/#\/schema\/person\/1df7cc9f6c6e5901ce19062096c025af","name":"Le Diamant","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.lediamant.ca\/fr\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/987afa0f07c5e880e415fd6bbdc5cc7ccbd67354d810536804d8f515d64bd014?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/987afa0f07c5e880e415fd6bbdc5cc7ccbd67354d810536804d8f515d64bd014?s=96&d=mm&r=g","caption":"Le Diamant"}}]}},"_links":{"self":[{"href":"https:\/\/www.lediamant.ca\/fr\/wp-json\/wp\/v2\/posts\/17478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lediamant.ca\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lediamant.ca\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lediamant.ca\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lediamant.ca\/fr\/wp-json\/wp\/v2\/comments?post=17478"}],"version-history":[{"count":44,"href":"https:\/\/www.lediamant.ca\/fr\/wp-json\/wp\/v2\/posts\/17478\/revisions"}],"predecessor-version":[{"id":22322,"href":"https:\/\/www.lediamant.ca\/fr\/wp-json\/wp\/v2\/posts\/17478\/revisions\/22322"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lediamant.ca\/fr\/wp-json\/wp\/v2\/media\/17658"}],"wp:attachment":[{"href":"https:\/\/www.lediamant.ca\/fr\/wp-json\/wp\/v2\/media?parent=17478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lediamant.ca\/fr\/wp-json\/wp\/v2\/categories?post=17478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lediamant.ca\/fr\/wp-json\/wp\/v2\/tags?post=17478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}